{"id":10949,"date":"2026-04-04T18:35:14","date_gmt":"2026-04-04T18:35:14","guid":{"rendered":"https:\/\/glass-a.com\/%d9%85%d9%86-%d9%86%d8%ad%d9%86-2\/"},"modified":"2026-05-08T20:51:35","modified_gmt":"2026-05-08T20:51:35","slug":"%d9%85%d9%86-%d9%86%d8%ad%d9%86-2","status":"publish","type":"page","link":"https:\/\/glass-a.com\/ar\/%d9%85%d9%86-%d9%86%d8%ad%d9%86-2\/","title":{"rendered":"\u0645\u0646 \u0646\u062d\u0646"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:30px;--awb-padding-bottom:0px;--awb-padding-top-small:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"max-width:calc( 1200px + 80px );margin-left: calc(-80px \/ 2 );margin-right: calc(-80px \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_3_5 3_5 fusion-flex-column fusion-animated\" style=\"--awb-padding-bottom:65px;--awb-padding-left:50px;--awb-bg-size:cover;--awb-width-large:60%;--awb-margin-top-large:0px;--awb-spacing-right-large:40px;--awb-margin-bottom-large:80px;--awb-spacing-left-large:40px;--awb-width-medium:60%;--awb-order-medium:0;--awb-spacing-right-medium:40px;--awb-margin-bottom-medium:70px;--awb-spacing-left-medium:40px;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:40px;--awb-margin-bottom-small:50px;--awb-spacing-left-small:40px;\" data-animationType=\"fadeIn\" data-animationDuration=\"1.0\" data-animationOffset=\"top-into-view\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1 fusion-text-no-margin\" style=\"--awb-content-alignment:right;--awb-font-size:var(--awb-typography2-font-size);--awb-line-height:var(--awb-typography2-line-height);--awb-letter-spacing:var(--awb-typography2-letter-spacing);--awb-text-transform:var(--awb-typography2-text-transform);--awb-margin-bottom:10px;--awb-text-font-family:var(--awb-typography2-font-family);--awb-text-font-weight:var(--awb-typography2-font-weight);--awb-text-font-style:var(--awb-typography2-font-style);\"><p class=\"qwen-markdown-heading\" style=\"text-align: right;\"><span class=\"qwen-markdown-text\">\u0639\u0646 \u062c\u0644\u0627\u0633 \u0627\u064a\u0647<\/span><\/p>\n<\/div><div class=\"fusion-title title fusion-title-1 fusion-sep-none fusion-title-text fusion-title-size-two\" style=\"--awb-margin-bottom-small:30px;\"><h2 class=\"fusion-title-heading title-heading-right\" style=\"margin:0;letter-spacing:-1px;text-transform:capitalize;\"><div>\n<div>\u0645\u0646 \u0646\u062d\u0646<\/div>\n<\/div><\/h2><\/div><div class=\"fusion-text fusion-text-2 fusion-text-no-margin\" style=\"--awb-content-alignment:right;--awb-margin-left:10%;\"><div>\n<p style=\"text-align: right;\">&nbsp;<\/p>\n<div style=\"text-align: right;\">\u062c\u0644\u0627\u0633 \u0627\u064a\u0647 \u0647\u064a \u0634\u0631\u0643\u0629 \u0645\u062a\u062e\u0635\u0635\u0629 \u0641\u064a \u0627\u0633\u062a\u064a\u0631\u0627\u062f \u0648\u062a\u0631\u0643\u064a\u0628 \u0632\u062c\u0627\u062c \u0627\u0644\u0633\u064a\u0643\u0648\u0631\u064a\u062a\u060c \u0648\u0627\u0644\u0645\u0631\u0627\u064a\u0627 \u0627\u0644\u0645\u0636\u064a\u0626\u0629\u060c \u0648\u0627\u0644\u062d\u0644\u0648\u0644 \u0627\u0644\u0632\u062c\u0627\u062c\u064a\u0629 \u0627\u0644\u0645\u062a\u0643\u0627\u0645\u0644\u0629 \u0644\u0644\u0645\u0634\u0627\u0631\u064a\u0639 \u0627\u0644\u0633\u0643\u0646\u064a\u0629 \u0648\u0627\u0644\u062a\u062c\u0627\u0631\u064a\u0629 \u0648\u0627\u0644\u0625\u062f\u0627\u0631\u064a\u0629 \u0641\u064a \u062c\u0645\u064a\u0639 \u0623\u0646\u062d\u0627\u0621 \u0645\u0635\u0631.<\/div>\n<div>\n<div style=\"text-align: left;\">\n<div style=\"text-align: right;\">\u0628\u0641\u0636\u0644 \u062e\u0628\u0631\u062a\u0646\u0627 \u0627\u0644\u0648\u0627\u0633\u0639\u0629 \u0641\u064a \u062a\u0646\u0641\u064a\u0630 \u0627\u0644\u0645\u0634\u0627\u0631\u064a\u0639 \u0648\u0641\u0642\u0627\u064b \u0644\u0644\u0645\u0648\u0627\u0635\u0641\u0627\u062a \u0627\u0644\u0641\u0646\u064a\u0629 \u0627\u0644\u0645\u0639\u062a\u0645\u062f\u0629 \u0648\u0645\u0639\u0627\u064a\u064a\u0631 \u0627\u0644\u062c\u0648\u062f\u0629 \u0627\u0644\u0639\u0627\u0644\u0645\u064a\u0629\u060c \u0646\u0641\u062e\u0631 \u0628\u062a\u0642\u062f\u064a\u0645 \u0623\u0639\u0644\u0649 \u0645\u0633\u062a\u0648\u064a\u0627\u062a \u0627\u0644\u0643\u0641\u0627\u0621\u0629 \u0648\u0627\u0644\u062c\u0648\u062f\u0629.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><ul style=\"--awb-line-height:27.2px;--awb-icon-width:27.2px;--awb-icon-height:27.2px;--awb-icon-margin:11.2px;--awb-content-margin:38.4px;--awb-circlecolor:var(--awb-color1);--awb-circle-yes-font-size:14.08px;\" class=\"fusion-checklist fusion-checklist-1 fusion-checklist-default type-icons\"><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-yes\"><i class=\"fusion-li-icon fa-check fas\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">\n<div>\n<div>\u0627\u0633\u062a\u064a\u0631\u0627\u062f \u0648\u062a\u0631\u0643\u064a\u0628 \u062c\u0645\u064a\u0639 \u0623\u0646\u0648\u0627\u0639 \u0627\u0644\u0632\u062c\u0627\u062c.<\/div>\n<\/div>\n<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-yes\"><i class=\"fusion-li-icon fa-check fas\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">\n<p>\u0643\u0628\u0627\u064a\u0646 \u0634\u0627\u0648\u0631 \u0648\u0645\u0631\u0627\u064a\u0627 \u0645\u0636\u064a\u0626\u0629.<\/p>\n<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-yes\"><i class=\"fusion-li-icon fa-check fas\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">\u0633\u0644\u0627\u0644\u0645 \u0648\u062f\u0631\u0627\u0628\u0632\u064a\u0646\u0627\u062a \u0632\u062c\u0627\u062c\u064a\u0629.<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-yes\"><i class=\"fusion-li-icon fa-check fas\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">\n<p>\u0642\u0648\u0627\u0637\u0639 \u0627\u0644\u0645\u0643\u0627\u062a\u0628 \u0648\u0627\u0644\u0648\u0627\u062c\u0647\u0627\u062a \u0627\u0644\u0632\u062c\u0627\u062c\u064a\u0629.<\/p>\n<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-yes\"><i class=\"fusion-li-icon fa-check fas\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">\n<p>\u0623\u0639\u0645\u0627\u0644 \u0627\u0644\u0633\u062a\u0627\u0646\u0644\u0633 \u0633\u062a\u064a\u0644 \u0648\u0627\u0644\u0628\u0631\u062c\u0648\u0644\u0627\u062a.<\/p>\n<\/div><\/li><\/ul><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_2_5 2_5 fusion-flex-column fusion-animated dany\" style=\"--awb-padding-top:110px;--awb-padding-right:130px;--awb-padding-bottom:372px;--awb-padding-left:130px;--awb-padding-top-medium:80px;--awb-padding-right-medium:80px;--awb-padding-bottom-medium:80px;--awb-padding-left-medium:80px;--awb-padding-top-small:48px;--awb-padding-right-small:20px;--awb-padding-bottom-small:138px;--awb-padding-left-small:48px;--awb-max-height:800px;--awb-overflow:hidden;--awb-bg-color:var(--awb-color1);--awb-bg-color-hover:var(--awb-color1);--awb-bg-image:linear-gradient(144deg, hsla(var(--awb-color1-h),var(--awb-color1-s),var(--awb-color1-l),calc(var(--awb-color1-a) - 75%)) 0%,hsla(var(--awb-color1-h),var(--awb-color1-s),var(--awb-color1-l),calc(var(--awb-color1-a) - 75%)) 100%);--awb-bg-position:center top;--awb-bg-size:cover;--awb-box-shadow:20px 20px 3px 11px var(--awb-color2);;--awb-border-radius:25px 25px 25px 25px;--awb-width-large:40%;--awb-margin-top-large:0px;--awb-spacing-right-large:40px;--awb-margin-bottom-large:34px;--awb-spacing-left-large:40px;--awb-width-medium:100%;--awb-order-medium:2;--awb-spacing-right-medium:40px;--awb-spacing-left-medium:40px;--awb-width-small:50%;--awb-order-small:1;--awb-spacing-right-small:13px;--awb-margin-bottom-small:40px;--awb-spacing-left-small:13px;\" data-animationType=\"fadeInUp\" data-animationDuration=\"1.3\" data-animationOffset=\"top-into-view\"><div class=\"awb-column__background-slider\" ><div class=\"awb-background-slider\" data-type=\"column\" data-loop=\"yes\" data-animation=\"fade\" data-slideshow-speed=\"5000\" data-animation-speed=\"800\" data-direction=\"up\" style=\"--awb-image-position:50% 50%;\"><div class=\"swiper-wrapper\"><div class=\"swiper-slide\"><img decoding=\"async\" width=\"1920\" height=\"2560\" src=\"https:\/\/glass-a.com\/wp-content\/uploads\/2026\/01\/IMG_1218-scaled.jpg\" class=\"awb-background-slider__image lazyload\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271920%27%20height%3D%272560%27%20viewBox%3D%270%200%201920%202560%27%3E%3Crect%20width%3D%271920%27%20height%3D%272560%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/glass-a.com\/wp-content\/uploads\/2026\/01\/IMG_1218-scaled.jpg\" data-srcset=\"https:\/\/glass-a.com\/wp-content\/uploads\/2026\/01\/IMG_1218-225x300.jpg 225w, https:\/\/glass-a.com\/wp-content\/uploads\/2026\/01\/IMG_1218-scaled-600x800.jpg 600w, https:\/\/glass-a.com\/wp-content\/uploads\/2026\/01\/IMG_1218-768x1024.jpg 768w, https:\/\/glass-a.com\/wp-content\/uploads\/2026\/01\/IMG_1218-1152x1536.jpg 1152w, https:\/\/glass-a.com\/wp-content\/uploads\/2026\/01\/IMG_1218-1536x2048.jpg 1536w, https:\/\/glass-a.com\/wp-content\/uploads\/2026\/01\/IMG_1218-scaled.jpg 1920w\" data-sizes=\"auto\" \/><\/div><\/div><\/div><\/div><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-center fusion-content-layout-column\"><div class=\"awb-column__content\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_1 1_1 fusion-flex-column fusion-animated\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:40px;--awb-margin-bottom-large:100px;--awb-spacing-left-large:40px;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:40px;--awb-margin-bottom-medium:70px;--awb-spacing-left-medium:40px;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:40px;--awb-margin-bottom-small:50px;--awb-spacing-left-small:40px;\" data-animationType=\"fadeInUp\" data-animationDuration=\"1.0\" data-animationOffset=\"top-into-view\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div style=\"text-align:center;\"><a class=\"fusion-button button-flat fusion-button-default-size button-custom fusion-button-default button-1 fusion-button-default-span fusion-button-default-type\" style=\"--button_accent_color:var(--awb-color8);--button_border_color:var(--awb-color8);--button_accent_hover_color:var(--awb-color1);--button_border_hover_color:var(--awb-color8);--button_border_width-top:2px;--button_border_width-right:2px;--button_border_width-bottom:2px;--button_border_width-left:2px;--button_gradient_top_color:rgba(255,182,0,0);--button_gradient_bottom_color:rgba(255,182,0,0);--button_gradient_top_color_hover:var(--awb-color8);--button_gradient_bottom_color_hover:var(--awb-color8);--button_font_size:18px;--button_padding-top:20px;--button_padding-right:40px;--button_padding-bottom:20px;--button_padding-left:40px;\" target=\"_self\" href=\"https:\/\/glass-a.com\/ar\/%d8%a7%d8%aa%d8%b5%d9%84-%d8%a8%d9%86%d8%a7-2\/\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">\u062a\u0648\u0627\u0635\u0644 \u0645\u0639\u0646\u0627 \u0644\u0627\u0633\u062a\u0634\u0627\u0631\u0629 \u0641\u0646\u064a\u0629<\/span><\/a><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_1_1 1_1 fusion-flex-column fusion-animated\" style=\"--awb-padding-top:60px;--awb-padding-right:60px;--awb-padding-bottom:40px;--awb-padding-left:60px;--awb-bg-color:hsla(var(--awb-color8-h),var(--awb-color8-s),calc( var(--awb-color8-l) + 96% ),var(--awb-color8-a));--awb-bg-color-hover:hsla(var(--awb-color8-h),var(--awb-color8-s),calc( var(--awb-color8-l) + 96% ),var(--awb-color8-a));--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:40px;--awb-margin-bottom-large:100px;--awb-spacing-left-large:40px;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:40px;--awb-spacing-left-medium:40px;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:40px;--awb-spacing-left-small:40px;\" data-animationType=\"fadeIn\" data-animationDuration=\"1.0\" data-animationOffset=\"top-into-view\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-counters-box counters-box row fusion-clearfix fusion-columns-4\" style=\"--awb-body-color:var(--awb-color8);--awb-border-color:rgba(255,255,255,0);--awb-color:var(--awb-color8);--awb-border-color:rgba(255,255,255,0);\"><div class=\"fusion-counter-box fusion-column col-counter-box counter-box-wrapper col-lg-3 col-md-3 col-sm-3\" data-animationOffset=\"top-into-view\"><div class=\"counter-box-container\"><div class=\"content-box-percentage content-box-counter\"><i class=\"counter-box-icon fontawesome-icon fa-tasks fas\" aria-hidden=\"true\"><\/i><span class=\"unit\">+<\/span><span class=\"display-counter\" data-value=\"300\" data-direction=\"up\" data-decimals=\"0\">0<\/span><\/div><div class=\"counter-box-content\">\u062a\u0645 \u062a\u0646\u0641\u064a\u0630 \u0627\u0644\u0645\u0634\u0627\u0631\u064a\u0639 \u0628\u0646\u062c\u0627\u062d<\/div><\/div><\/div><div class=\"fusion-counter-box fusion-column col-counter-box counter-box-wrapper col-lg-3 col-md-3 col-sm-3\" data-animationOffset=\"top-into-view\"><div class=\"counter-box-container\"><div class=\"content-box-percentage content-box-counter\"><i class=\"counter-box-icon fontawesome-icon fa-user-check fas\" aria-hidden=\"true\"><\/i><span class=\"unit\">+<\/span><span class=\"display-counter\" data-value=\"500\" data-direction=\"up\" data-decimals=\"0\">0<\/span><\/div><div class=\"counter-box-content\">\u0639\u0645\u0644\u0627\u0621 \u0631\u0627\u0636\u0648\u0646<\/div><\/div><\/div><div class=\"fusion-counter-box fusion-column col-counter-box counter-box-wrapper col-lg-3 col-md-3 col-sm-3\" data-animationOffset=\"top-into-view\"><div class=\"counter-box-container\"><div class=\"content-box-percentage content-box-counter\"><i class=\"counter-box-icon fontawesome-icon fa-boxes fas\" aria-hidden=\"true\"><\/i><span class=\"unit\">+<\/span><span class=\"display-counter\" data-value=\"10\" data-direction=\"up\" data-decimals=\"0\">0<\/span><\/div><div class=\"counter-box-content\">\u0627\u0644\u0645\u0646\u062a\u062c\u0627\u062a<\/div><\/div><\/div><div class=\"fusion-counter-box fusion-column col-counter-box counter-box-wrapper col-lg-3 col-md-3 col-sm-3\" data-animationOffset=\"top-into-view\"><div class=\"counter-box-container\"><div class=\"content-box-percentage content-box-counter\"><i class=\"counter-box-icon fontawesome-icon fa-star-half-alt fas\" aria-hidden=\"true\"><\/i><span class=\"display-counter\" data-value=\"100\" data-direction=\"up\" data-decimals=\"0\">0<\/span><span class=\"unit\">%<\/span><\/div><div class=\"counter-box-content\">\u0627\u0644\u062c\u0648\u062f\u0629<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-4 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:40px;--awb-margin-bottom-large:20px;--awb-spacing-left-large:40px;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:40px;--awb-spacing-left-medium:40px;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:40px;--awb-spacing-left-small:40px;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;width:100%;\"><div class=\"fusion-separator-border sep-shadow\" style=\"--awb-height:20px;--awb-amount:20px;background:radial-gradient(ellipse at 50% -50% , var(--awb-color3) 0px, rgba(255, 255, 255, 0) 80%) repeat scroll 0 0 rgba(0, 0, 0, 0);background:-webkit-radial-gradient(ellipse at 50% -50% , var(--awb-color3) 0px, rgba(255, 255, 255, 0) 80%) repeat scroll 0 0 rgba(0, 0, 0, 0);background:-moz-radial-gradient(ellipse at 50% -50% , var(--awb-color3) 0px, rgba(255, 255, 255, 0) 80%) repeat scroll 0 0 rgba(0, 0, 0, 0);background:-o-radial-gradient(ellipse at 50% -50% , var(--awb-color3) 0px, rgba(255, 255, 255, 0) 80%) repeat scroll 0 0 rgba(0, 0, 0, 0);\"><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:6%;--awb-padding-bottom:6%;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-stretch fusion-flex-content-wrap\" style=\"max-width:calc( 1200px + 80px );margin-left: calc(-80px \/ 2 );margin-right: calc(-80px \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-5 fusion_builder_column_1_2 1_2 fusion-flex-column fusion-animated\" style=\"--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:40px;--awb-margin-bottom-large:20px;--awb-spacing-left-large:40px;--awb-width-medium:50%;--awb-spacing-right-medium:40px;--awb-spacing-left-medium:40px;--awb-width-small:100%;--awb-spacing-right-small:40px;--awb-spacing-left-small:40px;\" data-animationType=\"fadeInRight\" data-animationDuration=\"1.0\" data-animationOffset=\"top-into-view\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-center fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-2 fusion-sep-none fusion-title-text fusion-title-size-three\"><h3 class=\"fusion-title-heading title-heading-right\" style=\"margin:0;text-transform:capitalize;\">\u0645\u0647\u0645\u062a\u0646\u0627<\/h3><\/div><div class=\"fusion-text fusion-text-3\" style=\"--awb-content-alignment:right;\"><div>\n<div>\u062a\u0642\u062f\u064a\u0645 \u0645\u0646\u062a\u062c\u0627\u062a \u0632\u062c\u0627\u062c \u0633\u064a\u0643\u0648\u0631\u064a\u062a \u0639\u0627\u0644\u064a\u0629 \u0627\u0644\u062c\u0648\u062f\u0629 \u0648\u062a\u0631\u0643\u064a\u0628\u0627\u062a \u0627\u062d\u062a\u0631\u0627\u0641\u064a\u0629.<\/div>\n<div>\n<p>\u062e\u062f\u0645\u0627\u062a \u062a\u062a\u062c\u0627\u0648\u0632 \u062a\u0648\u0642\u0639\u0627\u062a \u0627\u0644\u0639\u0645\u0644\u0627\u0621 \u0645\u0646 \u062e\u0644\u0627\u0644:<\/p>\n<div>\n<ul>\n<li>\u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u062e\u0627\u0645\u0627\u062a \u0645\u0639\u062a\u0645\u062f\u0629 \u0648\u0645\u062e\u062a\u0628\u0631\u0629 \u0644\u0636\u0645\u0627\u0646 \u0627\u0644\u0633\u0644\u0627\u0645\u0629 \u0641\u0642\u0637.<\/li>\n<li>\u062a\u0642\u062f\u064a\u0645 \u062d\u0644\u0648\u0644 \u0645\u062e\u0635\u0635\u0629 \u0645\u0635\u0645\u0645\u0629 \u062e\u0635\u064a\u0635\u0627\u064b \u0644\u062a\u0644\u0628\u064a\u0629 \u0627\u062d\u062a\u064a\u0627\u062c\u0627\u062a \u0643\u0644 \u0639\u0645\u064a\u0644.<\/li>\n<li>\u0627\u0644\u062d\u0641\u0627\u0638 \u0639\u0644\u0649 \u0623\u0633\u0639\u0627\u0631 \u062a\u0646\u0627\u0641\u0633\u064a\u0629 \u062f\u0648\u0646 \u0627\u0644\u0645\u0633\u0627\u0648\u0645\u0629 \u0639\u0644\u0649 \u0627\u0644\u062c\u0648\u062f\u0629.<\/li>\n<li> \u0636\u0645\u0627\u0646 \u0625\u062a\u0645\u0627\u0645 \u0627\u0644\u0645\u0634\u0627\u0631\u064a\u0639 \u0641\u064a \u0627\u0644\u0645\u0648\u0627\u0639\u064a\u062f \u0627\u0644\u0645\u062d\u062f\u062f\u0629 \u0645\u0639 \u0627\u0647\u062a\u0645\u0627\u0645 \u062f\u0642\u064a\u0642 \u0628\u0627\u0644\u062a\u0641\u0627\u0635\u064a\u0644.<\/li>\n<li> \u0628\u0646\u0627\u0621 \u0639\u0644\u0627\u0642\u0627\u062a \u0645\u0633\u062a\u062f\u0627\u0645\u0629 \u0645\u0646 \u062e\u0644\u0627\u0644 \u0627\u0644\u0634\u0641\u0627\u0641\u064a\u0629 \u0648\u0627\u0644\u0645\u0648\u062b\u0648\u0642\u064a\u0629.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-6 fusion_builder_column_1_2 1_2 fusion-flex-column fusion-animated dany\" style=\"--awb-padding-top:110px;--awb-padding-right:130px;--awb-padding-bottom:372px;--awb-padding-left:130px;--awb-padding-top-medium:80px;--awb-padding-right-medium:80px;--awb-padding-bottom-medium:80px;--awb-padding-left-medium:80px;--awb-padding-top-small:48px;--awb-padding-right-small:26px;--awb-padding-bottom-small:186px;--awb-padding-left-small:48px;--awb-max-height:800px;--awb-overflow:hidden;--awb-bg-color:var(--awb-color1);--awb-bg-color-hover:var(--awb-color1);--awb-bg-image:linear-gradient(144deg, hsla(var(--awb-color1-h),var(--awb-color1-s),var(--awb-color1-l),calc(var(--awb-color1-a) - 75%)) 0%,hsla(var(--awb-color1-h),var(--awb-color1-s),var(--awb-color1-l),calc(var(--awb-color1-a) - 75%)) 100%);--awb-bg-position:center top;--awb-bg-size:cover;--awb-box-shadow:20px 20px 3px 11px var(--awb-color2);;--awb-border-radius:25px 25px 25px 25px;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:40px;--awb-margin-bottom-large:34px;--awb-spacing-left-large:40px;--awb-width-medium:100%;--awb-order-medium:2;--awb-spacing-right-medium:40px;--awb-spacing-left-medium:40px;--awb-width-small:50%;--awb-order-small:1;--awb-spacing-right-small:60px;--awb-margin-bottom-small:40px;--awb-spacing-left-small:3px;\" data-animationType=\"fadeInUp\" data-animationDuration=\"1.3\" data-animationOffset=\"top-into-view\"><div class=\"awb-column__background-slider\" ><div class=\"awb-background-slider\" data-type=\"column\" data-loop=\"yes\" data-animation=\"fade\" data-slideshow-speed=\"5000\" data-animation-speed=\"800\" data-direction=\"up\" style=\"--awb-image-position:50% 50%;\"><div class=\"swiper-wrapper\"><div class=\"swiper-slide\"><img decoding=\"async\" width=\"817\" height=\"961\" src=\"https:\/\/glass-a.com\/wp-content\/uploads\/2026\/04\/brouchure-new.pdf-image-124.jpg\" class=\"awb-background-slider__image lazyload\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27817%27%20height%3D%27961%27%20viewBox%3D%270%200%20817%20961%27%3E%3Crect%20width%3D%27817%27%20height%3D%27961%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/glass-a.com\/wp-content\/uploads\/2026\/04\/brouchure-new.pdf-image-124.jpg\" data-srcset=\"https:\/\/glass-a.com\/wp-content\/uploads\/2026\/04\/brouchure-new.pdf-image-124-200x235.jpg 200w, https:\/\/glass-a.com\/wp-content\/uploads\/2026\/04\/brouchure-new.pdf-image-124-255x300.jpg 255w, https:\/\/glass-a.com\/wp-content\/uploads\/2026\/04\/brouchure-new.pdf-image-124-400x471.jpg 400w, https:\/\/glass-a.com\/wp-content\/uploads\/2026\/04\/brouchure-new.pdf-image-124-600x706.jpg 600w, https:\/\/glass-a.com\/wp-content\/uploads\/2026\/04\/brouchure-new.pdf-image-124-768x903.jpg 768w, https:\/\/glass-a.com\/wp-content\/uploads\/2026\/04\/brouchure-new.pdf-image-124-800x941.jpg 800w, https:\/\/glass-a.com\/wp-content\/uploads\/2026\/04\/brouchure-new.pdf-image-124.jpg 817w\" data-sizes=\"auto\" \/><\/div><\/div><\/div><\/div><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-center fusion-content-layout-column\"><div class=\"awb-column__content\"><div class=\"fusion-slider-sc\"><div class=\"fusion-flexslider-loading flexslider flexslider-hover-type-none\" data-slideshow_autoplay=\"1\" data-slideshow_smooth_height=\"0\" data-slideshow_speed=\"7000\" style=\"max-width:100%;height:100%;\"><ul class=\"slides\"><\/ul><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-3 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:6%;--awb-padding-bottom:6%;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-stretch fusion-flex-content-wrap\" style=\"max-width:calc( 1200px + 80px );margin-left: calc(-80px \/ 2 );margin-right: calc(-80px \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-7 fusion_builder_column_1_2 1_2 fusion-flex-column fusion-animated\" style=\"--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:40px;--awb-margin-bottom-large:20px;--awb-spacing-left-large:40px;--awb-width-medium:50%;--awb-spacing-right-medium:40px;--awb-spacing-left-medium:40px;--awb-width-small:100%;--awb-spacing-right-small:40px;--awb-spacing-left-small:40px;\" data-animationType=\"fadeInRight\" data-animationDuration=\"1.0\" data-animationOffset=\"top-into-view\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-center fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-3 fusion-sep-none fusion-title-text fusion-title-size-three\"><h3 class=\"fusion-title-heading title-heading-right\" style=\"margin:0;text-transform:capitalize;\">\u0631\u0624\u064a\u062a\u0646\u0627<\/h3><\/div><div class=\"fusion-text fusion-text-4\"><div>\n<p>&nbsp;<\/p>\n<div>\u0623\u0646 \u0646\u0643\u0648\u0646 \u0627\u0644\u0645\u0632\u0648\u062f \u0627\u0644\u0631\u0627\u0626\u062f \u0641\u064a \u0645\u0635\u0631 \u0644\u062d\u0644\u0648\u0644 \u0627\u0644\u0632\u062c\u0627\u062c \u0627\u0644\u0645\u0628\u062a\u0643\u0631\u0629\u060c \u0645\u0639\u0631\u0648\u0641\u064a\u0646 \u0628\u0627\u0644\u062a\u0632\u0627\u0645\u0646\u0627 \u0628\u0627\u0644\u062c\u0648\u062f\u0629 \u0648\u0627\u0644\u0633\u0644\u0627\u0645\u0629 \u0648\u0627\u0644\u062a\u0635\u0645\u064a\u0645 \u0627\u0644\u0639\u0635\u0631\u064a. \u0646\u0633\u0639\u0649 \u0644\u062a\u062d\u0648\u064a\u0644 \u0627\u0644\u0645\u0633\u0627\u062d\u0627\u062a<\/div>\n<div>\u0645\u0646 \u062e\u0644\u0627\u0644 \u0627\u0644\u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0627\u0644\u0623\u0646\u064a\u0642 \u0644\u0644\u0632\u062c\u0627\u062c \u0645\u0639 \u0627\u0644\u062d\u0641\u0627\u0638 \u0639\u0644\u0649 \u0623\u0639\u0644\u0649 \u0645\u0639\u0627\u064a\u064a\u0631 \u0627\u0644\u062d\u0631\u0641\u064a\u0629 \u0648\u062e\u062f\u0645\u0629 \u0627\u0644\u0639\u0645\u0644\u0627\u0621.<\/div>\n<\/div>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-8 fusion_builder_column_1_2 1_2 fusion-flex-column fusion-animated dany\" style=\"--awb-padding-top:110px;--awb-padding-right:130px;--awb-padding-bottom:372px;--awb-padding-left:130px;--awb-padding-top-medium:80px;--awb-padding-right-medium:80px;--awb-padding-bottom-medium:80px;--awb-padding-left-medium:80px;--awb-padding-top-small:48px;--awb-padding-right-small:48px;--awb-padding-bottom-small:194px;--awb-padding-left-small:48px;--awb-max-height:800px;--awb-overflow:hidden;--awb-bg-color:var(--awb-color1);--awb-bg-color-hover:var(--awb-color1);--awb-bg-image:linear-gradient(144deg, hsla(var(--awb-color1-h),var(--awb-color1-s),var(--awb-color1-l),calc(var(--awb-color1-a) - 75%)) 0%,hsla(var(--awb-color1-h),var(--awb-color1-s),var(--awb-color1-l),calc(var(--awb-color1-a) - 75%)) 100%);--awb-bg-position:center top;--awb-bg-size:cover;--awb-box-shadow:20px 20px 3px 11px var(--awb-color2);;--awb-border-radius:25px 25px 25px 25px;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:40px;--awb-margin-bottom-large:34px;--awb-spacing-left-large:40px;--awb-width-medium:100%;--awb-order-medium:2;--awb-spacing-right-medium:40px;--awb-spacing-left-medium:40px;--awb-width-small:50%;--awb-order-small:1;--awb-spacing-right-small:60px;--awb-margin-bottom-small:40px;--awb-spacing-left-small:3px;\" data-animationType=\"fadeInUp\" data-animationDuration=\"1.3\" data-animationOffset=\"top-into-view\"><div class=\"awb-column__background-slider\" ><div class=\"awb-background-slider\" data-type=\"column\" data-loop=\"yes\" data-animation=\"fade\" data-slideshow-speed=\"5000\" data-animation-speed=\"800\" data-direction=\"up\" style=\"--awb-image-position:50% 50%;\"><div class=\"swiper-wrapper\"><div class=\"swiper-slide\"><img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/glass-a.com\/wp-content\/uploads\/2026\/01\/FB_IMG_1719819264993-1.jpg\" class=\"awb-background-slider__image lazyload\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27500%27%20height%3D%27500%27%20viewBox%3D%270%200%20500%20500%27%3E%3Crect%20width%3D%27500%27%20height%3D%27500%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/glass-a.com\/wp-content\/uploads\/2026\/01\/FB_IMG_1719819264993-1.jpg\" data-srcset=\"https:\/\/glass-a.com\/wp-content\/uploads\/2026\/01\/FB_IMG_1719819264993-1-100x100.jpg 100w, https:\/\/glass-a.com\/wp-content\/uploads\/2026\/01\/FB_IMG_1719819264993-1-150x150.jpg 150w, https:\/\/glass-a.com\/wp-content\/uploads\/2026\/01\/FB_IMG_1719819264993-1-300x300.jpg 300w, https:\/\/glass-a.com\/wp-content\/uploads\/2026\/01\/FB_IMG_1719819264993-1.jpg 500w\" data-sizes=\"auto\" \/><\/div><\/div><\/div><\/div><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-center fusion-content-layout-column\"><div class=\"awb-column__content\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-4 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:6%;--awb-padding-bottom:6%;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-stretch fusion-flex-content-wrap\" style=\"max-width:calc( 1200px + 80px );margin-left: calc(-80px \/ 2 );margin-right: calc(-80px \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-9 fusion_builder_column_1_2 1_2 fusion-flex-column fusion-animated\" style=\"--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:40px;--awb-margin-bottom-large:20px;--awb-spacing-left-large:40px;--awb-width-medium:50%;--awb-spacing-right-medium:40px;--awb-spacing-left-medium:40px;--awb-width-small:100%;--awb-spacing-right-small:40px;--awb-spacing-left-small:40px;\" data-animationType=\"fadeInRight\" data-animationDuration=\"1.0\" data-animationOffset=\"top-into-view\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-center fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-4 fusion-sep-none fusion-title-text fusion-title-size-three\"><h3 class=\"fusion-title-heading title-heading-right\" style=\"margin:0;text-transform:capitalize;\"><div>\n<div>\u0644\u0645\u0627\u0630\u0627 \u062a\u062e\u062a\u0627\u0631 \u062c\u0644\u0627\u0633 \u0627\u064a\u0647\u061f<\/div>\n<\/div><\/h3><\/div><div class=\"fusion-text fusion-text-5\"><ol>\n<li><strong>\u0636\u0645\u0627\u0646 \u0627\u0644\u062c\u0648\u062f\u0629:<\/strong><br \/>\u0632\u062c\u0627\u062c \u0633\u064a\u0643\u0648\u0631\u064a\u062a \u0641\u0627\u062e\u0631 \u0648\u0645\u0639\u062a\u0645\u062f \u0648\u0641\u0642\u0627\u064b \u0644\u0645\u0639\u0627\u064a\u064a\u0631 \u0627\u0644\u0633\u0644\u0627\u0645\u0629 \u0627\u0644\u062f\u0648\u0644\u064a\u0629<\/li>\n<li> <strong>\u0641\u0631\u064a\u0642 \u0645\u0646 \u0627\u0644\u062e\u0628\u0631\u0627\u0621:<\/strong><br \/>\u0641\u0646\u064a\u0648\u0646 \u0645\u062d\u062a\u0631\u0641\u0648\u0646 \u064a\u062a\u0645\u062a\u0639\u0648\u0646 \u0628\u0633\u0646\u0648\u0627\u062a \u0645\u0646 \u0627\u0644\u062e\u0628\u0631\u0629 \u0627\u0644\u0645\u062a\u062e\u0635\u0635\u0629<\/li>\n<li><strong>\u062d\u0644\u0648\u0644 \u0645\u062e\u0635\u0635\u0629:<\/strong><br \/>\u062a\u0635\u0627\u0645\u064a\u0645 \u0645\u0641\u0635\u0644\u0629 \u0644\u062a\u0646\u0627\u0633\u0628 \u0645\u0642\u0627\u0633\u0627\u062a\u0643 \u0627\u0644\u062f\u0642\u064a\u0642\u0629 \u0648\u062a\u0641\u0636\u064a\u0644\u0627\u062a\u0643 \u0627\u0644\u062e\u0627\u0635\u0629<\/li>\n<li><strong>\u0623\u0633\u0639\u0627\u0631 \u062a\u0646\u0627\u0641\u0633\u064a\u0629:<\/strong><br \/>\u0623\u0641\u0636\u0644 \u0642\u064a\u0645\u0629 \u0645\u0642\u0627\u0628\u0644 \u0627\u0644\u0633\u0639\u0631 \u0645\u0639 \u0634\u0641\u0627\u0641\u064a\u0629 \u062a\u0627\u0645\u0629 \u0641\u064a \u0627\u0644\u062a\u0633\u0639\u064a\u0631<\/li>\n<li><strong>\u0627\u0644\u0636\u0645\u0627\u0646 \u0648\u0627\u0644\u062f\u0639\u0645:<\/strong><br \/>\u0636\u0645\u0627\u0646 \u0634\u0627\u0645\u0644 \u0648\u062e\u062f\u0645\u0629 \u0645\u0627 \u0628\u0639\u062f \u0627\u0644\u0628\u064a\u0639 \u0645\u062e\u0635\u0635\u0629<\/li>\n<li><strong>\u0625\u0646\u062c\u0627\u0632 \u0633\u0631\u064a\u0639:<\/strong><br \/>\u0625\u062a\u0645\u0627\u0645 \u0627\u0644\u0645\u0634\u0631\u0648\u0639 \u0628\u0643\u0641\u0627\u0621\u0629 \u0639\u0627\u0644\u064a\u0629 \u062f\u0648\u0646 \u0627\u0644\u0645\u0633\u0627\u0633 \u0628\u0645\u0639\u0627\u064a\u064a\u0631 \u0627\u0644\u062c\u0648\u062f\u0629<\/li>\n<\/ol>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-10 fusion_builder_column_1_2 1_2 fusion-flex-column fusion-animated dany\" style=\"--awb-padding-top:110px;--awb-padding-right:130px;--awb-padding-bottom:372px;--awb-padding-left:130px;--awb-padding-top-medium:80px;--awb-padding-right-medium:80px;--awb-padding-bottom-medium:80px;--awb-padding-left-medium:80px;--awb-padding-top-small:48px;--awb-padding-right-small:30px;--awb-padding-bottom-small:177px;--awb-padding-left-small:48px;--awb-max-height:800px;--awb-overflow:hidden;--awb-bg-color:var(--awb-color1);--awb-bg-color-hover:var(--awb-color1);--awb-bg-image:linear-gradient(144deg, hsla(var(--awb-color1-h),var(--awb-color1-s),var(--awb-color1-l),calc(var(--awb-color1-a) - 75%)) 0%,hsla(var(--awb-color1-h),var(--awb-color1-s),var(--awb-color1-l),calc(var(--awb-color1-a) - 75%)) 100%);--awb-bg-position:center top;--awb-bg-size:cover;--awb-box-shadow:20px 20px 3px 11px var(--awb-color2);;--awb-border-radius:25px 25px 25px 25px;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:40px;--awb-margin-bottom-large:34px;--awb-spacing-left-large:40px;--awb-width-medium:100%;--awb-order-medium:2;--awb-spacing-right-medium:40px;--awb-spacing-left-medium:40px;--awb-width-small:50%;--awb-order-small:1;--awb-spacing-right-small:60px;--awb-margin-bottom-small:63px;--awb-spacing-left-small:3px;\" data-animationType=\"fadeInUp\" data-animationDuration=\"1.3\" data-animationOffset=\"top-into-view\"><div class=\"awb-column__background-slider\" ><div class=\"awb-background-slider\" data-type=\"column\" data-loop=\"yes\" data-animation=\"fade\" data-slideshow-speed=\"5000\" data-animation-speed=\"800\" data-direction=\"up\" style=\"--awb-image-position:47% 73%;\"><div class=\"swiper-wrapper\"><div class=\"swiper-slide\"><img decoding=\"async\" width=\"1440\" height=\"1800\" src=\"https:\/\/glass-a.com\/wp-content\/uploads\/2026\/01\/IMG_8039.jpg\" class=\"awb-background-slider__image lazyload\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271440%27%20height%3D%271800%27%20viewBox%3D%270%200%201440%201800%27%3E%3Crect%20width%3D%271440%27%20height%3D%271800%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/glass-a.com\/wp-content\/uploads\/2026\/01\/IMG_8039.jpg\" data-srcset=\"https:\/\/glass-a.com\/wp-content\/uploads\/2026\/01\/IMG_8039-240x300.jpg 240w, https:\/\/glass-a.com\/wp-content\/uploads\/2026\/01\/IMG_8039-600x750.jpg 600w, https:\/\/glass-a.com\/wp-content\/uploads\/2026\/01\/IMG_8039-768x960.jpg 768w, https:\/\/glass-a.com\/wp-content\/uploads\/2026\/01\/IMG_8039-819x1024.jpg 819w, https:\/\/glass-a.com\/wp-content\/uploads\/2026\/01\/IMG_8039-1229x1536.jpg 1229w, https:\/\/glass-a.com\/wp-content\/uploads\/2026\/01\/IMG_8039.jpg 1440w\" data-sizes=\"auto\" \/><\/div><\/div><\/div><\/div><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-center fusion-content-layout-column\"><div class=\"awb-column__content\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-5 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:100px;--awb-padding-bottom:100px;--awb-padding-top-medium:70px;--awb-padding-bottom-medium:70px;--awb-padding-top-small:50px;--awb-padding-bottom-small:50px;--awb-background-color:var(--awb-color2);--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:calc( 1200px + 0px );margin-left: calc(-0px \/ 2 );margin-right: calc(-0px \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-11 fusion_builder_column_1_2 1_2 fusion-flex-column fusion-flex-align-self-center fusion-animated\" style=\"--awb-padding-top:80px;--awb-padding-right:80px;--awb-padding-bottom:80px;--awb-padding-left:80px;--awb-padding-top-small:30px;--awb-padding-right-small:30px;--awb-padding-bottom-small:30px;--awb-padding-left-small:30px;--awb-bg-color:hsla(var(--awb-color8-h),var(--awb-color8-s),calc( var(--awb-color8-l) + 96% ),var(--awb-color8-a));--awb-bg-color-hover:hsla(var(--awb-color8-h),var(--awb-color8-s),calc( var(--awb-color8-l) + 96% ),var(--awb-color8-a));--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:0px;--awb-margin-bottom-large:0px;--awb-spacing-left-large:0px;--awb-width-medium:50%;--awb-order-medium:0;--awb-spacing-right-medium:0px;--awb-spacing-left-medium:0px;--awb-width-small:100%;--awb-order-small:1;--awb-spacing-right-small:0px;--awb-spacing-left-small:0px;\" data-animationType=\"fadeInUp\" data-animationDuration=\"1.0\" data-animationOffset=\"top-into-view\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-center fusion-content-layout-column\"><div class=\"fusion-text fusion-text-6 fusion-text-no-margin\" style=\"--awb-content-alignment:right;--awb-font-size:var(--awb-typography2-font-size);--awb-line-height:var(--awb-typography2-line-height);--awb-letter-spacing:var(--awb-typography2-letter-spacing);--awb-text-transform:var(--awb-typography2-text-transform);--awb-margin-bottom:25px;--awb-text-font-family:var(--awb-typography2-font-family);--awb-text-font-weight:var(--awb-typography2-font-weight);--awb-text-font-style:var(--awb-typography2-font-style);\"><p>\u062e\u0628\u0631\u0627\u0621 \u0632\u062c\u0627\u062c \u0630\u0648\u0648 \u062e\u0628\u0631\u0629 \u0648\u0627\u0633\u0639\u0629<\/p>\n<\/div><div class=\"fusion-title title fusion-title-5 fusion-sep-none fusion-title-text fusion-title-size-two\" style=\"--awb-margin-top:-10px;--awb-margin-bottom:30px;--awb-margin-bottom-small:30px;\"><h2 class=\"fusion-title-heading title-heading-right\" style=\"margin:0;letter-spacing:-1px;text-transform:capitalize;\">\u062f\u0639\u0645 \u0627\u0644\u062e\u0628\u0631\u0627\u0621 \u0641\u064a \u0643\u0644 \u062e\u0637\u0648\u0629<\/h2><\/div><div class=\"fusion-separator\" style=\"align-self: flex-end;margin-right:auto;margin-bottom:50px;width:100%;max-width:80px;\"><div class=\"fusion-separator-border sep-single sep-solid\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:var(--awb-color4);border-color:var(--awb-color4);border-top-width:3px;\"><\/div><\/div><div class=\"fusion-text fusion-text-7 fusion-text-no-margin\" style=\"--awb-content-alignment:right;--awb-margin-bottom:30px;\"><p>\u0641\u064a GlassA\u060c \u0641\u0631\u064a\u0642\u0646\u0627 \u0627\u0644\u0645\u062a\u0641\u0627\u0646\u064a \u0645\u0644\u062a\u0632\u0645 \u0628\u062a\u0642\u062f\u064a\u0645 \u062e\u062f\u0645\u0629 \u0627\u0633\u062a\u062b\u0646\u0627\u0626\u064a\u0629 \u0645\u0646 \u0627\u0644\u0627\u0633\u062a\u0634\u0627\u0631\u0629 \u0625\u0644\u0649 \u0627\u0644\u062a\u0631\u0643\u064a\u0628. \u0646\u0642\u062f\u0645 \u0625\u0631\u0634\u0627\u062f\u0627\u062a \u0645\u062a\u062e\u0635\u0635\u0629 \u0644\u0645\u0633\u0627\u0639\u062f\u062a\u0643 \u0641\u064a \u0627\u062e\u062a\u064a\u0627\u0631 \u062d\u0644\u0648\u0644 \u0627\u0644\u0632\u062c\u0627\u062c \u0627\u0644\u0645\u062b\u0627\u0644\u064a\u0629 \u0644\u0645\u0633\u0627\u062d\u062a\u0643\u060c \u0645\u0639 \u0636\u0645\u0627\u0646 \u0627\u0644\u062c\u0648\u062f\u0629 \u0648\u0627\u0644\u0633\u0644\u0627\u0645\u0629 \u0648\u0627\u0644\u0631\u0636\u0627 \u0627\u0644\u062a\u0627\u0645.<\/p>\n<\/div><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"width:calc( 100% + 0px ) !important;max-width:calc( 100% + 0px ) !important;margin-left: calc(-0px \/ 2 );margin-right: calc(-0px \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-0 fusion_builder_column_inner_1_1 1_1 fusion-flex-column\" style=\"--awb-padding-top:20px;--awb-padding-right:20px;--awb-padding-bottom:20px;--awb-padding-left:20px;--awb-bg-color:var(--awb-color1);--awb-bg-color-hover:var(--awb-color1);--awb-bg-size:cover;--awb-border-color:var(--awb-color4);--awb-border-top:2px;--awb-border-right:2px;--awb-border-bottom:2px;--awb-border-left:2px;--awb-border-style:solid;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:0px;--awb-margin-bottom-large:0px;--awb-spacing-left-large:0px;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:0px;--awb-spacing-left-medium:0px;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:0px;--awb-spacing-left-small:0px;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><ul style=\"--awb-line-height:27.2px;--awb-icon-width:27.2px;--awb-icon-height:27.2px;--awb-icon-margin:11.2px;--awb-content-margin:38.4px;\" class=\"fusion-checklist fusion-checklist-2 fusion-checklist-default type-icons\"><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-no\"><i class=\"fusion-li-icon fa-user-shield fas\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">\n<p>\u0646\u062d\u0646 \u0645\u062d\u0628\u064a\u0648\u0646 \u0628\u0627\u0644\u0643\u0627\u0645\u0644 \u0648\u0645\u062c\u0647\u0632\u0648\u0646 \u0628\u0627\u0644\u0645\u0639\u062f\u0627\u062a \u0627\u0644\u0645\u0646\u0627\u0633\u0628\u0629.<\/p>\n<\/div><\/li><\/ul><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-1 fusion_builder_column_inner_1_1 1_1 fusion-flex-column\" style=\"--awb-padding-top:20px;--awb-padding-right:20px;--awb-padding-bottom:20px;--awb-padding-left:20px;--awb-bg-color:var(--awb-color1);--awb-bg-color-hover:var(--awb-color1);--awb-bg-size:cover;--awb-border-color:var(--awb-color4);--awb-border-top:2px;--awb-border-right:2px;--awb-border-bottom:2px;--awb-border-left:2px;--awb-border-style:solid;--awb-width-large:100%;--awb-margin-top-large:15px;--awb-spacing-right-large:0px;--awb-margin-bottom-large:20px;--awb-spacing-left-large:0px;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:0px;--awb-spacing-left-medium:0px;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:0px;--awb-spacing-left-small:0px;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><ul style=\"--awb-line-height:27.2px;--awb-icon-width:27.2px;--awb-icon-height:27.2px;--awb-icon-margin:11.2px;--awb-content-margin:38.4px;\" class=\"fusion-checklist fusion-checklist-3 fusion-checklist-default type-icons\"><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-no\"><i class=\"fusion-li-icon fa-user-tie fas\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">\n<p>\u062a\u0631\u0643\u064a\u0628 \u0627\u062d\u062a\u0631\u0627\u0641\u064a \u0645\u0639 \u062a\u063a\u0637\u064a\u0629 \u0627\u0644\u0636\u0645\u0627\u0646<\/p>\n<\/div><\/li><\/ul><\/div><\/div><\/div><div ><a class=\"fusion-button button-flat fusion-button-default-size button-default fusion-button-default button-2 fusion-button-default-span fusion-button-default-type\" target=\"_self\" href=\"https:\/\/glass-a.com\/ar\/%d8%a7%d8%aa%d8%b5%d9%84-%d8%a8%d9%86%d8%a7-2\/\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">\u0623\u0631\u0633\u0644 \u0644\u0646\u0627 \u0631\u0633\u0627\u0644\u0629<\/span><\/a><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-12 fusion_builder_column_1_2 1_2 fusion-flex-column fusion-flex-align-self-stretch fusion-animated\" style=\"--awb-padding-bottom-small:269px;--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:0px;--awb-margin-bottom-large:0px;--awb-spacing-left-large:0px;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:0px;--awb-spacing-left-medium:0px;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:0px;--awb-spacing-left-small:0px;\" data-animationType=\"fadeIn\" data-animationDuration=\"1.0\" data-animationOffset=\"top-into-view\"><div class=\"awb-column__background-slider\" ><div class=\"awb-background-slider\" data-type=\"column\" data-loop=\"yes\" data-animation=\"fade\" data-slideshow-speed=\"5000\" data-animation-speed=\"800\" data-direction=\"up\" style=\"--awb-image-position:50% 50%;\"><div class=\"swiper-wrapper\"><div class=\"swiper-slide\"><img decoding=\"async\" width=\"896\" height=\"1090\" src=\"https:\/\/glass-a.com\/wp-content\/uploads\/2026\/03\/Gemini_Generated_Image_852xu2852xu2852x-e1776205949794.png\" class=\"awb-background-slider__image lazyload\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27896%27%20height%3D%271090%27%20viewBox%3D%270%200%20896%201090%27%3E%3Crect%20width%3D%27896%27%20height%3D%271090%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/glass-a.com\/wp-content\/uploads\/2026\/03\/Gemini_Generated_Image_852xu2852xu2852x-e1776205949794.png\" data-srcset=\"https:\/\/glass-a.com\/wp-content\/uploads\/2026\/03\/Gemini_Generated_Image_852xu2852xu2852x-e1776205949794-200x243.png 200w, https:\/\/glass-a.com\/wp-content\/uploads\/2026\/03\/Gemini_Generated_Image_852xu2852xu2852x-e1776205949794-247x300.png 247w, https:\/\/glass-a.com\/wp-content\/uploads\/2026\/03\/Gemini_Generated_Image_852xu2852xu2852x-e1776205949794-400x487.png 400w, https:\/\/glass-a.com\/wp-content\/uploads\/2026\/03\/Gemini_Generated_Image_852xu2852xu2852x-e1776205949794-600x730.png 600w, https:\/\/glass-a.com\/wp-content\/uploads\/2026\/03\/Gemini_Generated_Image_852xu2852xu2852x-e1776205949794-768x934.png 768w, https:\/\/glass-a.com\/wp-content\/uploads\/2026\/03\/Gemini_Generated_Image_852xu2852xu2852x-e1776205949794-800x973.png 800w, https:\/\/glass-a.com\/wp-content\/uploads\/2026\/03\/Gemini_Generated_Image_852xu2852xu2852x-e1776205949794-842x1024.png 842w, https:\/\/glass-a.com\/wp-content\/uploads\/2026\/03\/Gemini_Generated_Image_852xu2852xu2852x-e1776205949794.png 896w\" data-sizes=\"auto\" \/><\/div><\/div><\/div><\/div><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"awb-column__content\"><div class=\"fusion-separator fusion-no-large-visibility fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-bottom:40vh;width:100%;\"><\/div><\/div><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"100-width.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-10949","page","type-page","status-publish","hentry"],"acf":[],"_hostinger_reach_plugin_has_subscription_block":false,"_hostinger_reach_plugin_is_elementor":false,"_links":{"self":[{"href":"https:\/\/glass-a.com\/ar\/wp-json\/wp\/v2\/pages\/10949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/glass-a.com\/ar\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/glass-a.com\/ar\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/glass-a.com\/ar\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/glass-a.com\/ar\/wp-json\/wp\/v2\/comments?post=10949"}],"version-history":[{"count":12,"href":"https:\/\/glass-a.com\/ar\/wp-json\/wp\/v2\/pages\/10949\/revisions"}],"predecessor-version":[{"id":11193,"href":"https:\/\/glass-a.com\/ar\/wp-json\/wp\/v2\/pages\/10949\/revisions\/11193"}],"wp:attachment":[{"href":"https:\/\/glass-a.com\/ar\/wp-json\/wp\/v2\/media?parent=10949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}